{"id":7,"count":53,"description":"Reisearten","link":"https:\/\/www.ferienhausmiete.de\/blog\/kategorie\/reisearten\/","name":"Reisearten","slug":"reisearten","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.ferienhausmiete.de\/blog\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ferienhausmiete.de\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.ferienhausmiete.de\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.ferienhausmiete.de\/blog\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}